{"id":34,"count":7,"description":"","link":"https:\/\/www.hidralgobel.com\/en\/category\/rampas-de-accesibilidad\/","name":"Ramps","slug":"rampas-de-accesibilidad","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rampas de accesibilidad archivos - Hidral Gobel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hidralgobel.com\/en\/category\/rampas-de-accesibilidad\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rampas de accesibilidad archivos - Hidral Gobel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hidralgobel.com\/en\/category\/rampas-de-accesibilidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Hidral Gobel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.hidralgobel.com\\\/category\\\/rampas-de-accesibilidad\\\/\",\"url\":\"https:\\\/\\\/www.hidralgobel.com\\\/category\\\/rampas-de-accesibilidad\\\/\",\"name\":\"Rampas de accesibilidad archivos - Hidral Gobel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hidralgobel.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hidralgobel.com\\\/category\\\/rampas-de-accesibilidad\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hidralgobel.com\\\/category\\\/rampas-de-accesibilidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.hidralgobel.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rampas de accesibilidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hidralgobel.com\\\/#website\",\"url\":\"https:\\\/\\\/www.hidralgobel.com\\\/\",\"name\":\"Hidral Gobel\",\"description\":\"Fabricamos soluciones de accesibilidad   para los viajeros con movilidad reducida.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hidralgobel.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hidralgobel.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hidralgobel.com\\\/#organization\",\"name\":\"Hidral Gobel\",\"url\":\"https:\\\/\\\/www.hidralgobel.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.hidralgobel.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hidralgobel.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logotipo-Hidral-Gobel-2023_sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/www.hidralgobel.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logotipo-Hidral-Gobel-2023_sin-fondo.png\",\"width\":1754,\"height\":1241,\"caption\":\"Hidral Gobel\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hidralgobel.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rampas de accesibilidad archivos - Hidral Gobel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hidralgobel.com\/en\/category\/rampas-de-accesibilidad\/","og_locale":"en_GB","og_type":"article","og_title":"Rampas de accesibilidad archivos - Hidral Gobel","og_url":"https:\/\/www.hidralgobel.com\/en\/category\/rampas-de-accesibilidad\/","og_site_name":"Hidral Gobel","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.hidralgobel.com\/category\/rampas-de-accesibilidad\/","url":"https:\/\/www.hidralgobel.com\/category\/rampas-de-accesibilidad\/","name":"Rampas de accesibilidad archivos - Hidral Gobel","isPartOf":{"@id":"https:\/\/www.hidralgobel.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.hidralgobel.com\/category\/rampas-de-accesibilidad\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hidralgobel.com\/category\/rampas-de-accesibilidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.hidralgobel.com\/"},{"@type":"ListItem","position":2,"name":"Rampas de accesibilidad"}]},{"@type":"WebSite","@id":"https:\/\/www.hidralgobel.com\/#website","url":"https:\/\/www.hidralgobel.com\/","name":"Hidral Gobel","description":"Fabricamos soluciones de accesibilidad   para los viajeros con movilidad reducida.","publisher":{"@id":"https:\/\/www.hidralgobel.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hidralgobel.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.hidralgobel.com\/#organization","name":"Hidral Gobel","url":"https:\/\/www.hidralgobel.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.hidralgobel.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.hidralgobel.com\/wp-content\/uploads\/2023\/04\/Logotipo-Hidral-Gobel-2023_sin-fondo.png","contentUrl":"https:\/\/www.hidralgobel.com\/wp-content\/uploads\/2023\/04\/Logotipo-Hidral-Gobel-2023_sin-fondo.png","width":1754,"height":1241,"caption":"Hidral Gobel"},"image":{"@id":"https:\/\/www.hidralgobel.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.hidralgobel.com\/en\/wp-json\/wp\/v2\/categories\/34","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hidralgobel.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.hidralgobel.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.hidralgobel.com\/en\/wp-json\/wp\/v2\/posts?categories=34"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}